{"id":243,"count":1,"description":"","link":"https:\/\/www.blog.oliverdiener.de\/index.php\/tag\/botanischer-garten\/","name":"Botanischer Garten","slug":"botanischer-garten","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/tags\/243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/posts?tags=243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}