{"id":162,"count":2,"description":"","link":"https:\/\/www.blog.oliverdiener.de\/index.php\/tag\/idylle\/","name":"Idylle","slug":"idylle","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/tags\/162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/posts?tags=162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}