{"id":725,"date":"2025-11-09T23:37:24","date_gmt":"2025-11-09T22:37:24","guid":{"rendered":"https:\/\/www.blog.oliverdiener.de\/?p=725"},"modified":"2025-11-09T23:42:19","modified_gmt":"2025-11-09T22:42:19","slug":"syndicate-2025-westfalenhallen-dortmund","status":"publish","type":"post","link":"https:\/\/www.blog.oliverdiener.de\/index.php\/2025\/11\/09\/syndicate-2025-westfalenhallen-dortmund\/","title":{"rendered":"SYNDICATE 2025 &#8211; Westfalenhallen, Dortmund"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"525\" height=\"296\" src=\"https:\/\/www.youtube.com\/embed\/IMCVW5TUKa4?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=de-DE&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>\n\n\n\n<p>Dieses Jahr ging es zur Syndicate nach Dortmund. Was f\u00fcr ein Erlebnis. Biere wurden Getrunken und das Tanzbein geschwungen. Alles an allem eine sehr gelungene Veranstaltung. Es wird sicherlich nicht der letzte Besuch gewesen sein.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieses Jahr ging es zur Syndicate nach Dortmund. Was f\u00fcr ein Erlebnis. Biere wurden Getrunken und das Tanzbein geschwungen. Alles an allem eine sehr gelungene Veranstaltung. Es wird sicherlich nicht der letzte Besuch gewesen sein.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[121,232],"tags":[284,283,150,149,285,147,286],"class_list":["post-725","post","type-post","status-publish","format-standard","hentry","category-ausfluege-urlaub","category-konzerte-festivals","tag-dj","tag-dortmund","tag-hardcore","tag-hardstyle","tag-syndicate","tag-techno","tag-westfallenhalle"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8OKft-bH","_links":{"self":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/posts\/725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/comments?post=725"}],"version-history":[{"count":3,"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/posts\/725\/revisions"}],"predecessor-version":[{"id":728,"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/posts\/725\/revisions\/728"}],"wp:attachment":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/media?parent=725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/categories?post=725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/tags?post=725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}