{"id":475,"date":"2020-07-27T21:50:48","date_gmt":"2020-07-27T19:50:48","guid":{"rendered":"https:\/\/www.blog.oliverdiener.de\/?p=475"},"modified":"2020-07-27T22:00:20","modified_gmt":"2020-07-27T20:00:20","slug":"kirnitzschtalbahn-lichtenhainer-wasserfall","status":"publish","type":"post","link":"https:\/\/www.blog.oliverdiener.de\/index.php\/2020\/07\/27\/kirnitzschtalbahn-lichtenhainer-wasserfall\/","title":{"rendered":"Kirnitzschtalbahn + Lichtenhainer Wasserfall"},"content":{"rendered":"\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_124551-1024x768.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_124551-1024x768.jpg\" alt=\"\" data-id=\"481\" data-link=\"https:\/\/www.blog.oliverdiener.de\/?attachment_id=481\" class=\"wp-image-481\" srcset=\"https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_124551-1024x768.jpg 1024w, https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_124551-300x225.jpg 300w, https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_124551-768x576.jpg 768w, https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_124551-1536x1152.jpg 1536w, https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_124551-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">Kirnitzschtalbahn <\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_134739-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_134739-2-768x1024.jpg\" alt=\"\" data-id=\"482\" data-full-url=\"https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_134739-2.jpg\" data-link=\"https:\/\/www.blog.oliverdiener.de\/?attachment_id=482\" class=\"wp-image-482\" srcset=\"https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_134739-2-768x1024.jpg 768w, https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_134739-2-225x300.jpg 225w, https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_134739-2-1152x1536.jpg 1152w, https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_134739-2-1536x2048.jpg 1536w, https:\/\/www.blog.oliverdiener.de\/wp-content\/uploads\/2020\/07\/IMG_20200726_134739-2.jpg 1732w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">Lichtenhainer Wasserfall<\/figcaption><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[121,5,34,6],"tags":[197,128,196,133,40,37,41],"class_list":["post-475","post","type-post","status-publish","format-standard","hentry","category-ausfluege-urlaub","category-bilder","category-landschaften","category-natur","tag-bad-schandau","tag-gebirge","tag-lichtenhainer-wasserfall","tag-saechsische-schweiz","tag-sommer","tag-sonne","tag-wandern"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8OKft-7F","_links":{"self":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/posts\/475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/comments?post=475"}],"version-history":[{"count":3,"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/posts\/475\/revisions"}],"predecessor-version":[{"id":592,"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/posts\/475\/revisions\/592"}],"wp:attachment":[{"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/media?parent=475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/categories?post=475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blog.oliverdiener.de\/index.php\/wp-json\/wp\/v2\/tags?post=475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}